{"id":16046,"date":"2026-05-13T10:42:31","date_gmt":"2026-05-13T08:42:31","guid":{"rendered":"https:\/\/romeinternational.it\/it\/?post_type=mec-events&#038;p=16046"},"modified":"2026-05-13T12:01:18","modified_gmt":"2026-05-13T10:01:18","slug":"barabara-de-rossi-in-a-ntigone-non-non-a","status":"publish","type":"mec-events","link":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/","title":{"rendered":"Barabara De Rossi in A (NTIGONE) = non non A"},"content":{"rendered":"\n<p>Evento organizzato nell&#8217;ambito della terza missione\/impatto sociale di Ateneo. A cura di CircgE e Real. In collaborazione con ITS Rossellini.<\/p>\n\n\n\n<p>Rara occasione per poter applaudire il talento di Barbara De Rossi. L\u2019attrice, attualmente in tourn\u00e9e nei teatri italiani con lo spettacolo \u201cMade in Italy\u201d (a fine mese torna nuovamente a Roma, al Teatro Olimpico, dopo le rappresentazioni di Milano e Napoli) sar\u00e0 per soli due giorni all\u2019Universit\u00e0 degli Studi Internazionali di Roma-Unint con una messa in scena di Prove di Spettacolo&nbsp;<strong>(A)ntigone = Non non A<\/strong>&nbsp;del regista Roberto M. Iannone.<\/p>\n\n\n\n<p>Nell\u2019Aula Magna dell\u2019Universit\u00e0, insieme a Barbara de Rossi con il ruolo di Tiresia (uomo e donna nel mito e sulla scena) ci saranno gli attori Fabio Bisogni, Antonella Civale, Lucandrea Martinelli, Salvatore Nocera Bracco e lo stesso regista, che legger\u00e0 in modo originale la tragedia.<\/p>\n\n\n\n<p>Si tratta di una messa in scena davvero particolare, che oltre alle doti attoriali sfrutter\u00e0 anche componenti tecnologiche. Prenderanno infatti parte allo spettacolo robot umanoidi che si muoveranno autonomamente sul palco e reciteranno brani interagendo con gli attori, e gli spettatori potranno anche godere, a un certo punto dello spettacolo, di un&#8217;esperienza totalmente immersiva grazie a visori Meta che saranno forniti dall\u2019universit\u00e0.<\/p>\n\n\n\n<p>Per riservare un posto cliccare <a href=\"https:\/\/www.eventbrite.it\/e\/biglietti-barabara-de-rossi-in-a-ntigone-non-non-a-1988818122542?aff=oddtdtcreator&amp;_gl=1*pkrfkd*_up*MQ..*_ga*MTA1NzczMzUwOC4xNzc3OTcyNDcx*_ga_TQVES5V6SH*czE3Nzc5NzI0NzAkbzEkZzEkdDE3Nzc5NzI0OTkkajMxJGwwJGgw\">QUI<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento organizzato nell&#8217;ambito della terza missione\/impatto sociale di Ateneo. A cura di CircgE e Real. In collaborazione con ITS Rossellini. Rara occasione per poter applaudire il talento di Barbara De Rossi. L\u2019attrice, attualmente in tourn\u00e9e nei teatri italiani con lo spettacolo \u201cMade in Italy\u201d (a fine mese torna nuovamente a Roma, al Teatro Olimpico, dopo [&#8230;]\n","protected":false},"author":1,"featured_media":16047,"comment_status":"closed","ping_status":"closed","template":"","tags":[165,20,21,182],"mec_category":[11],"class_list":["post-16046","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-arte","tag-copertina","tag-evidenziato","tag-teatro","mec_category-spettacoli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barabara De Rossi in A (NTIGONE) = non non A - Rome International<\/title>\n<meta name=\"description\" content=\"Rara occasione per poter applaudire il talento di Barbara De Rossi. L\u2019attrice, attualmente in tourn\u00e9e nei teatri italiani con lo spettacolo \u201cMade in Italy\u201d (a fine mese torna nuovamente a Roma, al Teatro Olimpico, dopo le rappresentazioni di Milano e Napoli) sar\u00e0 per soli due giorni all\u2019Universit\u00e0 degli Studi Internazionali di Roma-Unint con una messa in scena di Prove di Spettacolo\u00a0(A)ntigone = Non non A\u00a0del regista Roberto M. Iannone.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barabara De Rossi in A (NTIGONE) = non non A - Rome International\" \/>\n<meta property=\"og:description\" content=\"Rara occasione per poter applaudire il talento di Barbara De Rossi. L\u2019attrice, attualmente in tourn\u00e9e nei teatri italiani con lo spettacolo \u201cMade in Italy\u201d (a fine mese torna nuovamente a Roma, al Teatro Olimpico, dopo le rappresentazioni di Milano e Napoli) sar\u00e0 per soli due giorni all\u2019Universit\u00e0 degli Studi Internazionali di Roma-Unint con una messa in scena di Prove di Spettacolo\u00a0(A)ntigone = Non non A\u00a0del regista Roberto M. Iannone.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Rome International\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:01:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Antigone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"515\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/barabara-de-rossi-in-a-ntigone-non-non-a\\\/\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/barabara-de-rossi-in-a-ntigone-non-non-a\\\/\",\"name\":\"Barabara De Rossi in A (NTIGONE) = non non A - Rome International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/barabara-de-rossi-in-a-ntigone-non-non-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/barabara-de-rossi-in-a-ntigone-non-non-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Antigone.jpg\",\"datePublished\":\"2026-05-13T08:42:31+00:00\",\"dateModified\":\"2026-05-13T10:01:18+00:00\",\"description\":\"Rara occasione per poter applaudire il talento di Barbara De Rossi. L\u2019attrice, attualmente in tourn\u00e9e nei teatri italiani con lo spettacolo \u201cMade in Italy\u201d (a fine mese torna nuovamente a Roma, al Teatro Olimpico, dopo le rappresentazioni di Milano e Napoli) sar\u00e0 per soli due giorni all\u2019Universit\u00e0 degli Studi Internazionali di Roma-Unint con una messa in scena di Prove di Spettacolo\u00a0(A)ntigone = Non non A\u00a0del regista Roberto M. Iannone.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/barabara-de-rossi-in-a-ntigone-non-non-a\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/barabara-de-rossi-in-a-ntigone-non-non-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/barabara-de-rossi-in-a-ntigone-non-non-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Antigone.jpg\",\"contentUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Antigone.jpg\",\"width\":515,\"height\":726},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/barabara-de-rossi-in-a-ntigone-non-non-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barabara De Rossi in A (NTIGONE) = non non A\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\",\"name\":\"Rome International\",\"description\":\"La guida agli eventi nella capitale\",\"publisher\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#organization\",\"name\":\"Planet Diplomacy srls\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Rome-Int-1440-1.png\",\"contentUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Rome-Int-1440-1.png\",\"width\":1440,\"height\":270,\"caption\":\"Planet Diplomacy srls\"},\"image\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barabara De Rossi in A (NTIGONE) = non non A - Rome International","description":"Rara occasione per poter applaudire il talento di Barbara De Rossi. L\u2019attrice, attualmente in tourn\u00e9e nei teatri italiani con lo spettacolo \u201cMade in Italy\u201d (a fine mese torna nuovamente a Roma, al Teatro Olimpico, dopo le rappresentazioni di Milano e Napoli) sar\u00e0 per soli due giorni all\u2019Universit\u00e0 degli Studi Internazionali di Roma-Unint con una messa in scena di Prove di Spettacolo\u00a0(A)ntigone = Non non A\u00a0del regista Roberto M. Iannone.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/","og_locale":"it_IT","og_type":"article","og_title":"Barabara De Rossi in A (NTIGONE) = non non A - Rome International","og_description":"Rara occasione per poter applaudire il talento di Barbara De Rossi. L\u2019attrice, attualmente in tourn\u00e9e nei teatri italiani con lo spettacolo \u201cMade in Italy\u201d (a fine mese torna nuovamente a Roma, al Teatro Olimpico, dopo le rappresentazioni di Milano e Napoli) sar\u00e0 per soli due giorni all\u2019Universit\u00e0 degli Studi Internazionali di Roma-Unint con una messa in scena di Prove di Spettacolo\u00a0(A)ntigone = Non non A\u00a0del regista Roberto M. Iannone.","og_url":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/","og_site_name":"Rome International","article_modified_time":"2026-05-13T10:01:18+00:00","og_image":[{"width":515,"height":726,"url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Antigone.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/","url":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/","name":"Barabara De Rossi in A (NTIGONE) = non non A - Rome International","isPartOf":{"@id":"https:\/\/romeinternational.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/#primaryimage"},"image":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/#primaryimage"},"thumbnailUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Antigone.jpg","datePublished":"2026-05-13T08:42:31+00:00","dateModified":"2026-05-13T10:01:18+00:00","description":"Rara occasione per poter applaudire il talento di Barbara De Rossi. L\u2019attrice, attualmente in tourn\u00e9e nei teatri italiani con lo spettacolo \u201cMade in Italy\u201d (a fine mese torna nuovamente a Roma, al Teatro Olimpico, dopo le rappresentazioni di Milano e Napoli) sar\u00e0 per soli due giorni all\u2019Universit\u00e0 degli Studi Internazionali di Roma-Unint con una messa in scena di Prove di Spettacolo\u00a0(A)ntigone = Non non A\u00a0del regista Roberto M. Iannone.","breadcrumb":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/#primaryimage","url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Antigone.jpg","contentUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Antigone.jpg","width":515,"height":726},{"@type":"BreadcrumbList","@id":"https:\/\/romeinternational.it\/it\/eventi\/barabara-de-rossi-in-a-ntigone-non-non-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/romeinternational.it\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/romeinternational.it\/it\/eventi\/"},{"@type":"ListItem","position":3,"name":"Barabara De Rossi in A (NTIGONE) = non non A"}]},{"@type":"WebSite","@id":"https:\/\/romeinternational.it\/it\/#website","url":"https:\/\/romeinternational.it\/it\/","name":"Rome International","description":"La guida agli eventi nella capitale","publisher":{"@id":"https:\/\/romeinternational.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/romeinternational.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/romeinternational.it\/it\/#organization","name":"Planet Diplomacy srls","url":"https:\/\/romeinternational.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/romeinternational.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2021\/09\/Rome-Int-1440-1.png","contentUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2021\/09\/Rome-Int-1440-1.png","width":1440,"height":270,"caption":"Planet Diplomacy srls"},"image":{"@id":"https:\/\/romeinternational.it\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec-events\/16046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/comments?post=16046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/media\/16047"}],"wp:attachment":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/media?parent=16046"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/tags?post=16046"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec_category?post=16046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}