{"id":16044,"date":"2026-05-13T10:17:54","date_gmt":"2026-05-13T08:17:54","guid":{"rendered":"https:\/\/romeinternational.it\/it\/?post_type=mec-events&#038;p=16044"},"modified":"2026-05-13T10:17:56","modified_gmt":"2026-05-13T08:17:56","slug":"italia-e-francia-di-fronte-alla-libia","status":"publish","type":"mec-events","link":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/","title":{"rendered":"Italia e Francia di fronte alla Libia"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Italia e Francia di fronte alla Libia. Dall\u2019Ottocento ad oggi a cura di Jean-Pierre Darnis e Jeremy Guedj<br><\/h2>\n\n\n\n<p>La Fondazione Craxi organizza un incontro il 22 maggio alle ore 17 presso la Stampa Estera nel quale verr\u00e0 presentato il nuovo volume &#8220;<em><strong>Italia e Francia di fronte alla Libia<\/strong><\/em>&#8220;.<\/p>\n\n\n\n<p>In occasione della pubblicazione del volume<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Italia e Francia di fronte alla Libia. Dall\u2019Ottocento ad oggi a cura di Jean-Pierre Darnis e Jeremy Guedj La Fondazione Craxi organizza un incontro il 22 maggio alle ore 17 presso la Stampa Estera nel quale verr\u00e0 presentato il nuovo volume &#8220;Italia e Francia di fronte alla Libia&#8220;. In occasione della pubblicazione del volume<\/p>\n","protected":false},"author":1,"featured_media":16045,"comment_status":"closed","ping_status":"closed","template":"","tags":[20,21,150,153],"mec_category":[45],"class_list":["post-16044","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-copertina","tag-evidenziato","tag-libri","tag-politica","mec_category-presentazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Italia e Francia di fronte alla Libia - Rome International<\/title>\n<meta name=\"description\" content=\"La Fondazione Craxi organizza un incontro il 22 maggio alle ore 17 presso la Stampa Estera nel quale verr\u00e0 presentato il nuovo volume &quot;Italia e Francia di fronte alla Libia&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italia e Francia di fronte alla Libia - Rome International\" \/>\n<meta property=\"og:description\" content=\"La Fondazione Craxi organizza un incontro il 22 maggio alle ore 17 presso la Stampa Estera nel quale verr\u00e0 presentato il nuovo volume &quot;Italia e Francia di fronte alla Libia&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rome International\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:17:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1880\" \/>\n\t<meta property=\"og:image:height\" content=\"940\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/italia-e-francia-di-fronte-alla-libia\\\/\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/italia-e-francia-di-fronte-alla-libia\\\/\",\"name\":\"Italia e Francia di fronte alla Libia - Rome International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/italia-e-francia-di-fronte-alla-libia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/italia-e-francia-di-fronte-alla-libia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image.png\",\"datePublished\":\"2026-05-13T08:17:54+00:00\",\"dateModified\":\"2026-05-13T08:17:56+00:00\",\"description\":\"La Fondazione Craxi organizza un incontro il 22 maggio alle ore 17 presso la Stampa Estera nel quale verr\u00e0 presentato il nuovo volume \\\"Italia e Francia di fronte alla Libia\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/italia-e-francia-di-fronte-alla-libia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/italia-e-francia-di-fronte-alla-libia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/italia-e-francia-di-fronte-alla-libia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image.png\",\"contentUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image.png\",\"width\":1880,\"height\":940},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/italia-e-francia-di-fronte-alla-libia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Italia e Francia di fronte alla Libia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\",\"name\":\"Rome International\",\"description\":\"La guida agli eventi nella capitale\",\"publisher\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#organization\",\"name\":\"Planet Diplomacy srls\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Rome-Int-1440-1.png\",\"contentUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Rome-Int-1440-1.png\",\"width\":1440,\"height\":270,\"caption\":\"Planet Diplomacy srls\"},\"image\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Italia e Francia di fronte alla Libia - Rome International","description":"La Fondazione Craxi organizza un incontro il 22 maggio alle ore 17 presso la Stampa Estera nel quale verr\u00e0 presentato il nuovo volume \"Italia e Francia di fronte alla Libia\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/","og_locale":"it_IT","og_type":"article","og_title":"Italia e Francia di fronte alla Libia - Rome International","og_description":"La Fondazione Craxi organizza un incontro il 22 maggio alle ore 17 presso la Stampa Estera nel quale verr\u00e0 presentato il nuovo volume \"Italia e Francia di fronte alla Libia\".","og_url":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/","og_site_name":"Rome International","article_modified_time":"2026-05-13T08:17:56+00:00","og_image":[{"width":1880,"height":940,"url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/image.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/","url":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/","name":"Italia e Francia di fronte alla Libia - Rome International","isPartOf":{"@id":"https:\/\/romeinternational.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/#primaryimage"},"image":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/#primaryimage"},"thumbnailUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/image.png","datePublished":"2026-05-13T08:17:54+00:00","dateModified":"2026-05-13T08:17:56+00:00","description":"La Fondazione Craxi organizza un incontro il 22 maggio alle ore 17 presso la Stampa Estera nel quale verr\u00e0 presentato il nuovo volume \"Italia e Francia di fronte alla Libia\".","breadcrumb":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/#primaryimage","url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/image.png","contentUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/image.png","width":1880,"height":940},{"@type":"BreadcrumbList","@id":"https:\/\/romeinternational.it\/it\/eventi\/italia-e-francia-di-fronte-alla-libia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/romeinternational.it\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/romeinternational.it\/it\/eventi\/"},{"@type":"ListItem","position":3,"name":"Italia e Francia di fronte alla Libia"}]},{"@type":"WebSite","@id":"https:\/\/romeinternational.it\/it\/#website","url":"https:\/\/romeinternational.it\/it\/","name":"Rome International","description":"La guida agli eventi nella capitale","publisher":{"@id":"https:\/\/romeinternational.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/romeinternational.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/romeinternational.it\/it\/#organization","name":"Planet Diplomacy srls","url":"https:\/\/romeinternational.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/romeinternational.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2021\/09\/Rome-Int-1440-1.png","contentUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2021\/09\/Rome-Int-1440-1.png","width":1440,"height":270,"caption":"Planet Diplomacy srls"},"image":{"@id":"https:\/\/romeinternational.it\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec-events\/16044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/comments?post=16044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/media\/16045"}],"wp:attachment":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/media?parent=16044"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/tags?post=16044"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec_category?post=16044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}