{"id":16041,"date":"2026-05-13T09:27:55","date_gmt":"2026-05-13T07:27:55","guid":{"rendered":"https:\/\/romeinternational.it\/it\/?post_type=mec-events&#038;p=16041"},"modified":"2026-05-13T09:27:57","modified_gmt":"2026-05-13T07:27:57","slug":"dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia","status":"publish","type":"mec-events","link":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/","title":{"rendered":"Dimensione istituzionale, politica e simbolica della partecipazione dell&#8217;America Latina alla Biennale di Venezia"},"content":{"rendered":"\n<p>Presso l&#8217;istituto IILA di Roma il 14 maggio alle ore 17:30 si terr\u00e0 la conferenza che approfondir\u00e0 il tema dell&#8217;importanza della partecipazione dell&#8217;America Latina alla Biennale di Venezia. La conferenza si terr\u00e0 presso la biblioteca <\/p>\n\n\n\n<p>Per maggiori info sui relatori e su come partecipare vai sul sito dell&#8217;IILA cliccando <a href=\"https:\/\/iila.org\/it\/\">QUI<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"800\" src=\"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/MAIL-CHIMP-614x1024-1-480x800.jpg\" alt=\"\" class=\"wp-image-16042\" srcset=\"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/MAIL-CHIMP-614x1024-1-480x800.jpg 480w, https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/MAIL-CHIMP-614x1024-1-240x400.jpg 240w, https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/MAIL-CHIMP-614x1024-1.jpg 614w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Presso l&#8217;istituto IILA di Roma il 14 maggio alle ore 17:30 si terr\u00e0 la conferenza che approfondir\u00e0 il tema dell&#8217;importanza della partecipazione dell&#8217;America Latina alla Biennale di Venezia. La conferenza si terr\u00e0 presso la biblioteca Per maggiori info sui relatori e su come partecipare vai sul sito dell&#8217;IILA cliccando QUI<\/p>\n","protected":false},"author":1,"featured_media":16043,"comment_status":"closed","ping_status":"closed","template":"","tags":[165,20,21],"mec_category":[9],"class_list":["post-16041","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-arte","tag-copertina","tag-evidenziato","mec_category-convegni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dimensione istituzionale, politica e simbolica della partecipazione dell&#039;America Latina alla Biennale di Venezia - Rome International<\/title>\n<meta name=\"description\" content=\"Presso l&#039;istituto IILA di Roma il 14 maggio alle ore 17:30 si terr\u00e0 la conferenza che approfondir\u00e0 il tema dell&#039;importanza della partecipazione dell&#039;America Latina alla Biennale di Venezia. La conferenza si terr\u00e0 presso la biblioteca\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dimensione istituzionale, politica e simbolica della partecipazione dell&#039;America Latina alla Biennale di Venezia - Rome International\" \/>\n<meta property=\"og:description\" content=\"Presso l&#039;istituto IILA di Roma il 14 maggio alle ore 17:30 si terr\u00e0 la conferenza che approfondir\u00e0 il tema dell&#039;importanza della partecipazione dell&#039;America Latina alla Biennale di Venezia. La conferenza si terr\u00e0 presso la biblioteca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rome International\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T07:27:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Padiglione-Centrale_Giardini_Photo-by-Francesco-Galli-700x603-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\\\/\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\\\/\",\"name\":\"Dimensione istituzionale, politica e simbolica della partecipazione dell'America Latina alla Biennale di Venezia - Rome International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Padiglione-Centrale_Giardini_Photo-by-Francesco-Galli-700x603-1.jpg\",\"datePublished\":\"2026-05-13T07:27:55+00:00\",\"dateModified\":\"2026-05-13T07:27:57+00:00\",\"description\":\"Presso l'istituto IILA di Roma il 14 maggio alle ore 17:30 si terr\u00e0 la conferenza che approfondir\u00e0 il tema dell'importanza della partecipazione dell'America Latina alla Biennale di Venezia. La conferenza si terr\u00e0 presso la biblioteca\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Padiglione-Centrale_Giardini_Photo-by-Francesco-Galli-700x603-1.jpg\",\"contentUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Padiglione-Centrale_Giardini_Photo-by-Francesco-Galli-700x603-1.jpg\",\"width\":700,\"height\":603},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dimensione istituzionale, politica e simbolica della partecipazione dell&#8217;America Latina alla Biennale di Venezia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\",\"name\":\"Rome International\",\"description\":\"La guida agli eventi nella capitale\",\"publisher\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#organization\",\"name\":\"Planet Diplomacy srls\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Rome-Int-1440-1.png\",\"contentUrl\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Rome-Int-1440-1.png\",\"width\":1440,\"height\":270,\"caption\":\"Planet Diplomacy srls\"},\"image\":{\"@id\":\"https:\\\/\\\/romeinternational.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dimensione istituzionale, politica e simbolica della partecipazione dell'America Latina alla Biennale di Venezia - Rome International","description":"Presso l'istituto IILA di Roma il 14 maggio alle ore 17:30 si terr\u00e0 la conferenza che approfondir\u00e0 il tema dell'importanza della partecipazione dell'America Latina alla Biennale di Venezia. La conferenza si terr\u00e0 presso la biblioteca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/","og_locale":"it_IT","og_type":"article","og_title":"Dimensione istituzionale, politica e simbolica della partecipazione dell'America Latina alla Biennale di Venezia - Rome International","og_description":"Presso l'istituto IILA di Roma il 14 maggio alle ore 17:30 si terr\u00e0 la conferenza che approfondir\u00e0 il tema dell'importanza della partecipazione dell'America Latina alla Biennale di Venezia. La conferenza si terr\u00e0 presso la biblioteca","og_url":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/","og_site_name":"Rome International","article_modified_time":"2026-05-13T07:27:57+00:00","og_image":[{"width":700,"height":603,"url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Padiglione-Centrale_Giardini_Photo-by-Francesco-Galli-700x603-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/","url":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/","name":"Dimensione istituzionale, politica e simbolica della partecipazione dell'America Latina alla Biennale di Venezia - Rome International","isPartOf":{"@id":"https:\/\/romeinternational.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/#primaryimage"},"image":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/#primaryimage"},"thumbnailUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Padiglione-Centrale_Giardini_Photo-by-Francesco-Galli-700x603-1.jpg","datePublished":"2026-05-13T07:27:55+00:00","dateModified":"2026-05-13T07:27:57+00:00","description":"Presso l'istituto IILA di Roma il 14 maggio alle ore 17:30 si terr\u00e0 la conferenza che approfondir\u00e0 il tema dell'importanza della partecipazione dell'America Latina alla Biennale di Venezia. La conferenza si terr\u00e0 presso la biblioteca","breadcrumb":{"@id":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/#primaryimage","url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Padiglione-Centrale_Giardini_Photo-by-Francesco-Galli-700x603-1.jpg","contentUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2026\/05\/Padiglione-Centrale_Giardini_Photo-by-Francesco-Galli-700x603-1.jpg","width":700,"height":603},{"@type":"BreadcrumbList","@id":"https:\/\/romeinternational.it\/it\/eventi\/dimensione-istituzionale-politica-e-simbolica-della-partecipazione-dellamerica-latina-alla-biennale-di-venezia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/romeinternational.it\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/romeinternational.it\/it\/eventi\/"},{"@type":"ListItem","position":3,"name":"Dimensione istituzionale, politica e simbolica della partecipazione dell&#8217;America Latina alla Biennale di Venezia"}]},{"@type":"WebSite","@id":"https:\/\/romeinternational.it\/it\/#website","url":"https:\/\/romeinternational.it\/it\/","name":"Rome International","description":"La guida agli eventi nella capitale","publisher":{"@id":"https:\/\/romeinternational.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/romeinternational.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/romeinternational.it\/it\/#organization","name":"Planet Diplomacy srls","url":"https:\/\/romeinternational.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/romeinternational.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2021\/09\/Rome-Int-1440-1.png","contentUrl":"https:\/\/romeinternational.it\/it\/wp-content\/uploads\/2021\/09\/Rome-Int-1440-1.png","width":1440,"height":270,"caption":"Planet Diplomacy srls"},"image":{"@id":"https:\/\/romeinternational.it\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec-events\/16041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/comments?post=16041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/media\/16043"}],"wp:attachment":[{"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/media?parent=16041"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/tags?post=16041"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/romeinternational.it\/it\/wp-json\/wp\/v2\/mec_category?post=16041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}